{"id":9916,"date":"2019-04-03T14:44:20","date_gmt":"2019-04-03T12:44:20","guid":{"rendered":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/?p=9916"},"modified":"2019-04-03T14:44:28","modified_gmt":"2019-04-03T12:44:28","slug":"face-au-g7-defendons-nos-alternatives-st-malo-le-6-avril","status":"publish","type":"post","link":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/04\/03\/face-au-g7-defendons-nos-alternatives-st-malo-le-6-avril\/","title":{"rendered":"\u00ab\u00a0Face au G7, d\u00e9fendons nos alternatives !\u00a0\u00bb St-Malo le 6 avril"},"content":{"rendered":"\n<h4 style=\"text-align:center\"><strong>Stop les guerres, Stop les violences, Stop la mis\u00e8re <br>Ratification du Trait\u00e9 d\u2019interdiction des armes nucl\u00e9aires ! <br>Dissolution de l\u2019OTAN ! PAIX !<\/strong><\/h4>\n\n\n\n<p class=\"has-background has-pale-cyan-blue-background-color\"><strong>Sur la base de ce texte les d\u00e9fenseurs de la Paix, de la plan\u00e8te et du progr\u00e8s social ont rendez-vous \u00e0 St-Malo le samedi 6 avril 14h30 sur la jet\u00e9e, devant le centre nautique (la surf-school), plage de la Hoguette (suivre les Thermes marins).<\/strong><\/p>\n\n\n\n<p>A l\u2019Invitation du Ministre fran\u00e7ais Le Drian, les ministres des affaires \u00e9trang\u00e8res de 7 des plus grandes puissances \u00e9conomiques et militaires se r\u00e9unissent les 6 et 7 avril \u00e0 Dinard. \u00c0 l&rsquo;ordre du jour la lutte contre les in\u00e9galit\u00e9s et pour la paix, deux objectifs incompatibles avec les politiques imp\u00e9rialistes de militarisation, de domination du monde et les dogmes d&rsquo;un lib\u00e9ralisme \u00e9conomique dont la recherche du profit maximum semble \u00eatre l&rsquo;objectif unique au d\u00e9triment des droits humains. En effet l\u2019immense aspiration des peuples \u00e0 vivre ensemble en paix dans la solidarit\u00e9, la justice et la fraternit\u00e9 se heurte de front \u00e0 la volont\u00e9 de ces 7 puissances (dont 3 \u00c9tats dot\u00e9s de l\u2019arme nucl\u00e9aire). Ces \u00c9tats entendent dominer et organiser le monde par-dessus les peuples et les \u00c9tats au nom d\u2019int\u00e9r\u00eats \u00e9conomiques, financiers, g\u00e9ostrat\u00e9giques et militaires qui ne sont pas ceux des peuples. Ils tentent de mettre \u00e9galement sur la touche les Nations Unies qui regroupent les 193 \u00c9tats de la Plan\u00e8te. De plus ce regroupement des 7 puissances n\u2019a aucune l\u00e9gitimit\u00e9 en termes de droit international et de multilat\u00e9ralisme tel qu\u2019exprim\u00e9 par la Charte des Nations Unies.<\/p>\n\n\n\n<p class=\"has-text-color has-vivid-cyan-blue-color\"><strong>Le G7 (\u00ab\u00a0Groupe des sept\u00a0\u00bb)<\/strong> est un groupe de discussion et de partenariat \u00e9conomique de 7 pays r\u00e9put\u00e9s \u00eatre les plus grandes puissances avanc\u00e9es du monde qui d\u00e9tiennent environ les 2\/3 de la richesse nette mondiale : Allemagne, Canada, USA, France, Italie, Japon, et Royaume Uni.<\/p>\n\n\n\n<h3 style=\"text-align:center\">R\u00e9volte et indignation<\/h3>\n\n\n\n<p><strong>Nous sommes r\u00e9volt\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>par le fait que, dans un monde regorgeant de richesses et de connaissances scientifiques et techniques, un milliards de personnes vivent dans le d\u00e9nuement le plus total, la faim et l\u2019analphab\u00e9tisme.<\/li><li>par l\u2019augmentation incessante des d\u00e9penses militaires qui sont pass\u00e9es de 1144 milliards de dollars en 2001 \u00e0 1800 milliards en 2018 (SIPRI, le Stockholm International Peace Research Institute) et favorisent un commerce des armes immoral et dangereux, alors que le budget des Nations Unies pour les op\u00e9rations de paix est de seulement 8,7 milliards<\/li><li>Par la reprise de la course aux armement nucl\u00e9aires pour laquelle les puissances nucl\u00e9aires ont pr\u00e9vus de d\u00e9penser de l\u2019ordre de 1000 milliards de dollars dans les ann\u00e9es \u00e0 venir.<\/li><li>de savoir que seulement 5 % des d\u00e9penses militaires mondiales pendant 10 ans permettraient selon le programme des Nations Unies pour le d\u00e9veloppement (PNUD) de r\u00e9soudre les principaux probl\u00e8mes de l\u2019humanit\u00e9 (alimentation en eau, faim, analphab\u00e9tisme, principales maladies\u2026).<\/li><li>par la persistance de guerres qui conduisent au chaos et enfantent des monstruosit\u00e9s dont sont victimes les populations civiles jet\u00e9es sur le chemin de l\u2019exil<\/li><\/ul>\n\n\n\n<p><strong>Nous sommes solidaires<\/strong> de ces populations qui doivent affronter des violences inou\u00efes et la mort dans les oc\u00e9ans ou au pied des murs qui se construisent \u00e0 travers le monde (USA, Palestine, Frontex..), faute de la volont\u00e9 des puissants de ce monde dont le G7 de d\u00e9gager les ressources et les moyens n\u00e9cessaires alors qu\u2019en quelques jours ils trouvent les moyens de lever des armadas pour la guerre.<\/p>\n\n\n\n<p><strong>Nous sommes conscients<\/strong> que le d\u00e9r\u00e8glement climatique et les armes atomiques menacent la survie m\u00eame de l&rsquo;humanit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-attachment-id=\"9925\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/04\/03\/face-au-g7-defendons-nos-alternatives-st-malo-le-6-avril\/milliardaires-poussez\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/milliardaires-poussez.jpg\" data-orig-size=\"700,562\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"milliardaires-poussez\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/milliardaires-poussez-300x241.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/milliardaires-poussez.jpg\" decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"562\" src=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/milliardaires-poussez.jpg\" alt=\"les ressources sont limit\u00e9s\" class=\"wp-image-9925\" srcset=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/milliardaires-poussez.jpg 700w, https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/milliardaires-poussez-300x241.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<h3 style=\"text-align:center\">Alertes<\/h3>\n\n\n\n<p><strong>Nous alertons<\/strong> sur le fait que la Paix, le d\u00e9veloppement durable, la r\u00e9alisation des Objectifs du D\u00e9veloppement Durable, l\u2019\u00e9radication de la mis\u00e8re et la r\u00e9alisation des droits humains, la fin des in\u00e9galit\u00e9s de d\u00e9veloppement entre \u00c9tats et les continents, la lutte contre les d\u00e9r\u00e8glements climatiques sont inconciliables avec :<\/p>\n\n\n\n<ul><li>le niveau des d\u00e9penses militaires mondiales,<\/li><li>l\u2019existence des armes nucl\u00e9aires,<\/li><li>l\u2019accumulation de p\u00f4les de richesses entre les mains de quelques centaines d\u2019oligarques, de banques et de soci\u00e9t\u00e9s multinationales qui se comportent en v\u00e9ritables pr\u00e9dateurs.<\/li><\/ul>\n\n\n\n<p><strong>Nous alertons<\/strong> aussi :<\/p>\n\n\n\n<ul><li>sur le fait que la paix est \u00e9galement incompatible avec la persistance d\u2019agences militaires ill\u00e9gales telle que l\u2019OTAN qui pousse \u00e0 la guerre et \u00e0 la militarisation des relations internationales depuis 70 ans.<\/li><li>sur la n\u00e9cessit\u00e9 de s\u2019opposer \u00e0 la privatisation des industries d\u2019armement qui favorise le commerce des armes<\/li><li>sur la n\u00e9cessit\u00e9 de d\u00e9fendre les principes de la Charte des Nations Unies comme fondement de la vie internationale et les Nations Unies comme lieu privil\u00e9gi\u00e9 de l\u2019exercice du multilat\u00e9ralisme,<\/li><\/ul>\n\n\n\n<h3 style=\"text-align:center\">Propositions et rassemblement<\/h3>\n\n\n\n<p>La mondialisation \u00e9conomique caract\u00e9ris\u00e9e par la recherche du profit imm\u00e9diat et maximum \u00e9crase les peuples, les met en concurrence mais ne permet pas de faire face aux d\u00e9fis du monde actuel (faim, s\u00e9curit\u00e9 environnementale et d\u00e9r\u00e8glement climatique, \u00e9ducation pour tous, promotion des \u00e9nergies renouvelables, objectifs de d\u00e9veloppement durable, r\u00e9alisation concr\u00e8te des droits humains ). La mondialisation de la militarisation des relations internationales fait porter aux peuples le fardeau de d\u00e9penses militaires d\u00e9mesur\u00e9es.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-attachment-id=\"9923\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/04\/03\/face-au-g7-defendons-nos-alternatives-st-malo-le-6-avril\/lutter-pour-la-paix\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/lutter-pour-la-paix.jpg\" data-orig-size=\"700,394\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"lutter-pour-la-paix\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/lutter-pour-la-paix-300x169.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/lutter-pour-la-paix.jpg\" decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/lutter-pour-la-paix.jpg\" alt=\"lutter pour la paix + la paix bordel\" class=\"wp-image-9923\" srcset=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/lutter-pour-la-paix.jpg 700w, https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/lutter-pour-la-paix-300x169.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p>Face \u00e0 cette situation<strong> les peuples doivent s\u2019unir et agir<\/strong> pour obtenir des politiques sociales, \u00e9conomiques, culturelles et de paix s\u2019inspirant de la <strong>Charte des Nations Unies<\/strong> et n\u00e9cessaires pour le respect et le d\u00e9veloppement de tous les droits humains et en premier lieu du <strong>droit de l\u2019homme \u00e0 la paix<\/strong> autour d\u2019 objectifs prioritaires et <strong>pour cela exiger :<\/strong><\/p>\n\n\n\n<ul><li>L\u2019arr\u00eat des logiques de puissance et de domination en remettant au centre de la vie international le respect des principes de la Charte des Nations Unies ce qui implique de faire rentrer le FMI et la banque mondiale dans la logique du syst\u00e8me des Nations Unies<\/li><li>la mise en oeuvre des principales r\u00e9solutions des Nations Unies en faveur de la paix au plan mondial ou pour le r\u00e8glement pacifique des conflits en premier lieu du conflit Isra\u00e9lo-Palestinien et au Yemen.<\/li><li>les moyens n\u00e9cessaires pour la r\u00e9alisation des 17 objectifs du d\u00e9veloppement durable adopt\u00e9s \u00e0 l\u2019ONU en d\u00e9cembre 2015<\/li><li>Partout un accueil digne pour les migrants et r\u00e9fugi\u00e9s<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img data-attachment-id=\"7679\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2016\/10\/28\/communique-halte-aux-bombardements-a-alep-au-yemen-ou-a-mossoul\/solidarite-migrants-refugie\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/solidarite-migrants-refugie.jpg\" data-orig-size=\"640,167\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"migreants et refugies fuient les guerres et la misere, solidarite\" data-image-description=\"&lt;p&gt;migreants et refugies fuient les guerres et la misere, solidarite&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/solidarite-migrants-refugie-300x78.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/solidarite-migrants-refugie.jpg\" decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"167\" src=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/solidarite-migrants-refugie.jpg\" alt=\"migreants et refugies fuient les guerres et la misere, solidarite\" class=\"wp-image-7679\" srcset=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/solidarite-migrants-refugie.jpg 640w, https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/solidarite-migrants-refugie-300x78.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<ul><li>les immenses moyens financiers et potentiels humains, scientifiques et technologiques n\u00e9cessaires pour faire face aux d\u00e9fis du d\u00e9r\u00e8glement climatique y compris en transf\u00e9rant une partie des budgets militaires.<\/li><li>une diminution drastique des d\u00e9penses militaires et l\u2019arr\u00eat imm\u00e9diat de tous les programmes de modernisation des armes nucl\u00e9aires (dans le respect de l\u2019article 6 du TNP, Trait\u00e9 de non-prolif\u00e9ration nucl\u00e9aire)<\/li><li>La ratification du Trait\u00e9 d\u2019interdiction des armes nucl\u00e9aires adopt\u00e9 le 7 juillet 2017 \u00e0 l\u2019ONU premier pas vers l\u2019\u00e9limination de ces armes de destruction massive, dangereuses, inhumaines, ill\u00e9gales, co\u00fbteuses et moralement inadmissibles qui menacent l\u2019existence m\u00eame de l\u2019humanit\u00e9.<\/li><li>l\u2019arr\u00eat de la militarisation de l\u2019UE, la mise en oeuvre d\u2019une conf\u00e9rence Helsinki 2 pour la paix et la s\u00e9curit\u00e9 commune en Europe incluant tous les pays de l\u2019Europe g\u00e9ographique et visant \u00e0 l\u2019instauration de nouvelles politiques mutuellement avantageuses avec les pays de l\u2019espace m\u00e9diterran\u00e9en et d\u2019Afrique.<\/li><li>la mise en oeuvre de politiques favorables \u00e0 la construction de la paix conform\u00e9ment \u00e0 la r\u00e9solution des Nations Unies de 2000 en faveur d\u2019une culture de la paix qui pr\u00e9voit que ces politiques doivent viser \u00e0 :<ul><li>Renforcer la culture de la paix par l\u2019\u00e9ducation<\/li><li>Promouvoir la paix et la s\u00e9curit\u00e9 internationales en s\u2019appuyant sur les acquis en mati\u00e8re de s\u00e9curit\u00e9 humaine et de d\u00e9sarmement<\/li><li>Promouvoir le respect de tous les droits humains<\/li><li>Promouvoir le d\u00e9veloppement \u00e9conomique et social durable \u00e0 travers en particulier la mise en oeuvre et la g\u00e9n\u00e9ralisation de services publics de protection sociale et de syst\u00e8mes publics de gestion des biens communs mondiaux<\/li><li>Assurer l\u2019\u00e9galit\u00e9 entre les hommes et les femmes<\/li><li>Favoriser la participation d\u00e9mocratique dans tous les secteurs de la soci\u00e9t\u00e9 (et la protection des lanceurs d\u2019alertes &#8211; ndlr)<\/li><li>D\u00e9velopper la compr\u00e9hension, la tol\u00e9rance et la solidarit\u00e9 entre tous les peuples et toutes les cultures \u00e0 travers le dialogue et l\u2019\u00e9change d\u2019informations en g\u00e9n\u00e9ralisant pour les jeunes des programmes de type Erasmus<\/li><li>Soutenir la communication participative et la libre circulation de l\u2019information et des connaissances incluant la promotion de la presse d\u2019opinion et la mise en commun des r\u00e9sultats scientifiques <\/li><\/ul><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img data-attachment-id=\"4280\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2013\/11\/21\/mouvement-de-la-paix-cyber-action-adressee-aux-parlementaires\/crayon-missile-300\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/Crayon-missile-300.gif\" data-orig-size=\"300,166\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"pas un sou pour de nouvelles bombes atomiques\" data-image-description=\"&lt;p&gt;pas un sou pour de nouvelles bombes atomiques&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/Crayon-missile-300.gif\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/Crayon-missile-300.gif\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"166\" src=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/Crayon-missile-300.gif\" alt=\"pas un sou pour de nouvelles bombes atomiques\" class=\"wp-image-4280\"\/><\/figure><\/div>\n\n\n\n<p>Texte \u00e9labor\u00e9 dans la cadre du s\u00e9minaire interr\u00e9gional \u00ab\u00a0Face au G7 d\u00e9fendons nos alternatives\u00a0\u00bb qui s\u2019est tenu le 31 mars 2019 \u00e0 Saint Malo \u00e0 l\u2019initiative du Mouvement de la Paix (collectif Ouest et Bretagne) et a r\u00e9uni 40 citoyens membres de 20 associations et organisations diff\u00e9rentes (Mouvement de la Paix, Enseignants pour la Paix, FSU, CGT, ATTAC, ARAC, LDH, MNLE, PCF, NPA, FI, Collectif National anti-OTAN, CRID, comit\u00e9s de Paix de Morlaix-Brest, Concarneau Cornouailles, Morbihan, Maine et Loire, Caen, Rennes, Saint Malo, et le Bureau National du Mouvement de la Paix.)<\/p>\n\n\n\n<p>Ces citoyens ont d\u00e9cid\u00e9 de cr\u00e9er un <em>\u00ab\u00a0Collectif inter-r\u00e9gional anti-G7 2019 -Bretagne &#8211; Pays de Loire\u00a0\u00bb<\/em> pour pr\u00e9parer la mobilisation du contre-sommet du G7 qui se d\u00e9roulera les 25 et 27 ao\u00fbt 2019 \u00e0 Biarritz et alerter la population \u00e0 travers cet appel.<\/p>\n\n\n\n<p>Pour suivre les activit\u00e9s du Collectif National \u00ab\u00a0face au G7 , d\u00e9fendons nos alternatives\u00a0\u00bb consultez le site du CRID qui coordonne :  <a href=\"http:\/\/alternativesg7.org\/index.php\/appel-a-mobilisation-pour-defendre-nos-alternatives-face-au-g7\/\">http:\/\/alternativesg7.org\/index.php\/appel-a-mobilisation-pour-defendre-nos-alternatives-face-au-g7\/<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-attachment-id=\"9920\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/04\/03\/face-au-g7-defendons-nos-alternatives-st-malo-le-6-avril\/31mars2019-stmalo\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/31mars2019-StMalo.jpg\" data-orig-size=\"700,393\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"31mars2019-StMalo\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/31mars2019-StMalo-300x168.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/31mars2019-StMalo.jpg\" decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"393\" src=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/31mars2019-StMalo.jpg\" alt=\"Une partie des participants au s\u00e9minaire de St-Malo le 31 mars 2019\" class=\"wp-image-9920\" srcset=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/31mars2019-StMalo.jpg 700w, https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/31mars2019-StMalo-300x168.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption>Une partie des participants au s\u00e9minaire de St-Malo le 31 mars 2019<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-color has-vivid-cyan-blue-color\"><strong>Sur la base de ce texte les d\u00e9fenseurs de la Paix, de la plan\u00e8te et du progr\u00e8s social ont rendez-vous \u00e0 St-Malo le samedi 6 avril 14h30 sur la jet\u00e9e, devant le centre nautique (la surf-school), plage de la Hoguette (suivre les Thermes marins).<\/strong> Ils rejoindront le rassemblement, organis\u00e9 par le collectif cotes d\u2019\u00e9meraude \u00ab\u00a0Refusons le G7 et son monde\u00a0\u00bb \u00e0 15h30 avec drapeaux et banderoles.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-attachment-id=\"9921\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/04\/03\/face-au-g7-defendons-nos-alternatives-st-malo-le-6-avril\/eliminer-arme-atomique\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/eliminer-arme-atomique.jpg\" data-orig-size=\"700,98\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"eliminer-arme-atomique\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/eliminer-arme-atomique-300x42.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/eliminer-arme-atomique.jpg\" decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"98\" src=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/eliminer-arme-atomique.jpg\" alt=\"\u00e9liminer l'arme atomique pour pr\u00e9server les g\u00e9n\u00e9rations futures\" class=\"wp-image-9921\" srcset=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/eliminer-arme-atomique.jpg 700w, https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/eliminer-arme-atomique-300x42.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img data-attachment-id=\"9922\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/04\/03\/face-au-g7-defendons-nos-alternatives-st-malo-le-6-avril\/france-doit-ratifier-tian\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/france-doit-ratifier-tian.jpg\" data-orig-size=\"700,525\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"france-doit-ratifier-tian\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/france-doit-ratifier-tian-300x225.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/france-doit-ratifier-tian.jpg\" decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"525\" src=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/france-doit-ratifier-tian.jpg\" alt=\"la France doit ratifier le Trait\u00e9 d'interdiction des armes nucl\u00e9aires vot\u00e9 par l'ONU\" class=\"wp-image-9922\" srcset=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/france-doit-ratifier-tian.jpg 700w, https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/france-doit-ratifier-tian-300x225.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img data-attachment-id=\"9934\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/04\/03\/face-au-g7-defendons-nos-alternatives-st-malo-le-6-avril\/avenir-humanite-paix\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/avenir-humanite-paix.jpg\" data-orig-size=\"350,238\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"avenir-humanite-paix\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/avenir-humanite-paix-300x204.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/avenir-humanite-paix.jpg\" decoding=\"async\" loading=\"lazy\" width=\"350\" height=\"238\" src=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/avenir-humanite-paix.jpg\" alt=\"pour l'humanit\u00e9 il n'y a d'autre avenir que la paix\" class=\"wp-image-9934\" srcset=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/avenir-humanite-paix.jpg 350w, https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/avenir-humanite-paix-300x204.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Stop les guerres, Stop les violences, Stop la mis\u00e8re Ratification du Trait\u00e9 d\u2019interdiction des armes nucl\u00e9aires ! Dissolution de l\u2019OTAN ! PAIX ! Sur la base de ce texte les d\u00e9fenseurs de la Paix, de la plan\u00e8te et du progr\u00e8s social ont rendez-vous \u00e0 St-Malo le samedi 6 avril 14h30 sur la jet\u00e9e, devant le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[27,13,28,68,15,45,3,48,33,159,241],"tags":[6,7,267,14,225,226,11,96,17,62],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/9916"}],"collection":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/comments?post=9916"}],"version-history":[{"count":11,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/9916\/revisions"}],"predecessor-version":[{"id":9936,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/9916\/revisions\/9936"}],"wp:attachment":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/media?parent=9916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/categories?post=9916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/tags?post=9916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}