{"id":9787,"date":"2019-03-08T11:06:17","date_gmt":"2019-03-08T10:06:17","guid":{"rendered":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/?p=9787"},"modified":"2019-03-08T11:06:27","modified_gmt":"2019-03-08T10:06:27","slug":"communique-du-8-mars","status":"publish","type":"post","link":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/03\/08\/communique-du-8-mars\/","title":{"rendered":"Communiqu\u00e9 du 8 mars"},"content":{"rendered":"\n<h3 style=\"text-align:center\"><strong>COMMUNIQU\u00c9 DE PRESSE <\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img data-attachment-id=\"9792\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2019\/03\/08\/communique-du-8-mars\/maxnewsworldthree702213-293\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/maxnewsworldthree702213-293.jpg\" data-orig-size=\"699,393\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"maxnewsworldthree702213-293\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/maxnewsworldthree702213-293-300x169.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/maxnewsworldthree702213-293.jpg\" decoding=\"async\" loading=\"lazy\" width=\"699\" height=\"393\" src=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/maxnewsworldthree702213-293.jpg\" alt=\"les femmes luttent pour leurs droits\" class=\"wp-image-9792\" srcset=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/maxnewsworldthree702213-293.jpg 699w, https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/maxnewsworldthree702213-293-300x169.jpg 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><figcaption style=\"font-size:75%;\">(Image de maxnewsworldthree)<\/figcaption><\/figure>\n\n\n\n<h2><strong>En ce 8 mars 2019, le Mouvement de la Paix s\u2019associe aux luttes des femmes \u0153uvrant pour leurs droits<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img data-attachment-id=\"9604\" data-permalink=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/logo-mvtpaix-150\/\" data-orig-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/logo-mvtpaix-150.jpg\" data-orig-size=\"150,150\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"logo du Mouvement de la Paix\" data-image-description=\"&lt;p&gt;logo du Mouvement de la Paix&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/logo-mvtpaix-150.jpg\" data-large-file=\"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/logo-mvtpaix-150.jpg\" decoding=\"async\" loading=\"lazy\" width=\"150\" height=\"150\" src=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/logo-mvtpaix-150.jpg\" alt=\"logo du Mouvement de la Paix\" class=\"wp-image-9604\"\/><\/figure><\/div>\n\n\n\n<p>Les femmes sont parmi les plus pr\u00e9caires, ce sont elles qui\ntouchent les plus petites retraites, le temps partiel est le plus souvent\noccup\u00e9 par des femmes. A travail \u00e9gal, elles ont des salaires moins importants.\nLe r\u00e9f\u00e9rent familial dans les familles monoparentales est souvent une femme.<\/p>\n\n\n\n<p>Or, il ne peut pas y avoir\nconstruction de la paix sans l\u2019\u00e9galit\u00e9 r\u00e9elle entre les femmes et les hommes.\nIl faut donc appliquer la R\u00e9solution 53\/243 des Nations Unies (1999) relative \u00e0\nla culture de la paix d\u2019assurer l\u2019\u00e9galit\u00e9 entre les femmes et les hommes.<strong> <\/strong><\/p>\n\n\n\n<p>Les femmes sont encore les premi\u00e8res victimes de toutes les\nformes de violences. Lors des conflits arm\u00e9s, elles disposent souvent de moins\nde moyens pour se prot\u00e9ger. Avec les enfants, elles constituent g\u00e9n\u00e9ralement la\nmajorit\u00e9 des populations r\u00e9fugi\u00e9es ou d\u00e9plac\u00e9es. Elles sont la cible r\u00e9currente\nde tactiques guerri\u00e8res bas\u00e9es sur le viol comme arme de guerre. Elles sont le\nplus souvent tenues \u00e0 l\u2019\u00e9cart des n\u00e9gociations de paix, bien qu\u2019elles soient \u00e0\nla t\u00eate de mouvements pacifiques et \u00e0 l\u2019origine du rel\u00e8vement communautaire \u00e0 l\u2018issue\ndes conflits. Exclues des processus de reconstruction, les femmes ont moins de\nchances de reprendre une vie normale, d\u2019obtenir justice pour les violations de\nleurs droits fondamentaux et de contribuer \u00e0 la r\u00e9forme des lois et des\ninstitutions publiques.<\/p>\n\n\n\n<p>Malgr\u00e9 les diff\u00e9rentes d\u00e9clarations et lois sur l\u2019\u00e9galit\u00e9 femme-homme,\n\u00e0 commencer par la Constitution de 1958&nbsp;\n\u00ab&nbsp;<em>garantissant \u00e0 la femme,\ndans tous les domaines, des droits \u00e9gaux \u00e0 ceux de l\u2019homme<\/em>&nbsp;\u00bb, malgr\u00e9\ncelles plus r\u00e9centes sur la parit\u00e9, alors que les femmes n\u2019occupent toujours que\n25,6% des si\u00e8ges des parlements nationaux. Malgr\u00e9 le taux de scolarisation des\nfilles dans l\u2019enseignement sup\u00e9rieur qui d\u00e9passe celui des gar\u00e7ons, la conduite\ndes affaires publiques et notamment tout ce qui touche \u00e0 la s\u00e9curit\u00e9 est l\u2019affaire\ndes hommes avec souvent, une vision moins apais\u00e9e des relations humaines. Un champ\nd\u2019action immense s\u2019ouvre aux luttes des femmes appel\u00e9es \u00e0 prendre une place originale\navec les hommes dans les instances gouvernementales, et notamment dans les pr\u00e9ventions\net r\u00e8glement de conflits.<\/p>\n\n\n\n<p>Notre solidarit\u00e9 va plus particuli\u00e8rement aux femmes victimes de\nviolences sexistes, sexuelles et conjugales. Aujourd\u2019hui, une femme meurt tous\nles deux jours sous les coups de son partenaire ou ex-partenaire. Pour 2019, au\n3 mars, 30 femmes sont mortes assassin\u00e9es par leur partenaire ou ex-partenaire.\nEn 2017, 130 femmes ont \u00e9t\u00e9 tu\u00e9es par leur partenaire ou ex-partenaire intime\n\u00ab\u00a0officiel\u00a0\u00bb (conjoint, concubin, pacs\u00e9 ou \u00ab&nbsp;ex&nbsp;\u00bb) ou non\nofficiel (petits-amis, amants, relations \u00e9pisodiques&#8230;). Et l\u2019on ne peut pas\nfaire l\u2019impasse de l\u2019impact que cela engendre sur l\u2019enfant. En effet, l\u2019enfant\nest enfin consid\u00e9r\u00e9 comme co-victime des violences au sein du couple. 143&nbsp;000\nenfants vivent dans un foyer ou une femme a d\u00e9clar\u00e9 des violences physiques et\nsexuelles. 25 enfants mineurs sont d\u00e9c\u00e9d\u00e9s, tu\u00e9s par un de leurs parents dans\nun contexte de violences au sein du couple. Cette r\u00e9gression sociale touche de\nplein fouet les femmes.<\/p>\n\n\n\n<p>Enfin, Le Mouvement de la Paix se r\u00e9jouit du prix Nobel de la paix\n2018 attribu\u00e9 au docteur Denis Mukwege pour son travail aupr\u00e8s des femmes\nvictimes de viols en R\u00e9publique d\u00e9mocratique du Congo.<\/p>\n\n\n\n<p>Pour lutter contre toutes ces violences sexistes, sexuelles et conjugales,\npour la d\u00e9fense et la promotion des droits des femmes, Le Mouvement de la Paix\ns\u2019associe \u00e0 l\u2019initiative organis\u00e9e par les associations f\u00e9ministes de se\nrassembler ce vendredi 8 mars 2019, Place de la R\u00e9publique \u00e0 Paris, \u00e0 15h40,\nheure \u00e0 partir de laquelle les femmes ne sont plus pay\u00e9es, du fait des\nin\u00e9galit\u00e9s professionnelles et salariales.<\/p>\n\n\n\n<p>A Paris, le 7 mars 2019<\/p>\n\n\n\n<p><strong>Le Mouvement de la Paix<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMMUNIQU\u00c9 DE PRESSE (Image de maxnewsworldthree) En ce 8 mars 2019, le Mouvement de la Paix s\u2019associe aux luttes des femmes \u0153uvrant pour leurs droits Les femmes sont parmi les plus pr\u00e9caires, ce sont elles qui touchent les plus petites retraites, le temps partiel est le plus souvent occup\u00e9 par des femmes. A travail \u00e9gal, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[4,34,33,56,241],"tags":[76,23,8,101,264,9,10,17,57,12],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/9787"}],"collection":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/comments?post=9787"}],"version-history":[{"count":7,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/9787\/revisions"}],"predecessor-version":[{"id":9796,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/9787\/revisions\/9796"}],"wp:attachment":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/media?parent=9787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/categories?post=9787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/tags?post=9787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}