{"id":509,"date":"2012-05-07T12:00:05","date_gmt":"2012-05-07T10:00:05","guid":{"rendered":"http:\/\/culturedelapaix.org\/?p=509"},"modified":"2012-05-07T12:00:05","modified_gmt":"2012-05-07T10:00:05","slug":"commemoration-des-massacres-de-setif-a-rennes","status":"publish","type":"post","link":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/2012\/05\/07\/commemoration-des-massacres-de-setif-a-rennes\/","title":{"rendered":"Comm\u00e9moration des massacres de S\u00e9tif \u00e0 Rennes"},"content":{"rendered":"<p>Ne pas oublier que si le 8 mai est la journ\u00e9e en France de la victoire sur le fascisme c&rsquo;est h\u00e9las aussi la journ\u00e9e de comm\u00e9moration des massacres coloniaux de S\u00e9tif en mai 1945<\/p>\n<p><strong>Mardi 8 mai 2012<br \/>\n14 h 30<br \/>\nSquare de S\u00e9tif \u00e0 Rennes<br \/>\n(pr\u00e8s de la rue Marc Sangnier)<br \/>\nComm\u00e9moration fraternelle et pacifique: S\u00e9tif le 8 mai 1945<\/strong><\/p>\n<p><em>Alors que la France avec les peuples du monde f\u00eatait la fin du nazisme, la libert\u00e9 et la paix retrouv\u00e9es, des milliers d\u2019Alg\u00e9riens furent massacr\u00e9s le 8 mai 1945 \u00e0 S\u00e9tif et dans l\u2019Est de l\u2019Alg\u00e9rie. Une nouvelle p\u00e9riode de guerres et conflits coloniaux commen\u00e7ait&#8230;<\/em><\/p>\n<p><em>\u00ab\u00a0Si nous nous taisons, les murs pleureront.\u00a0\u00bb<\/em><\/p>\n<p><strong>14h30:<\/strong> Rassemblement, prise de parole unitaire et d\u00e9p\u00f4t de gerbe<br \/>\n<strong>15h45:<\/strong> MJC Br\u00e9quigny: Rencontre avec Monsieur BOUSBAH, S\u00e9tifien et t\u00e9moin de ces \u00e9v\u00e8nements \u00e0 S\u00e9tif en mai 1945; d\u00e9bat: questions-r\u00e9ponses<br \/>\n<strong>17h30:<\/strong> Pot de l\u2019amiti\u00e9<\/p>\n<p>Pour la m\u00e9moire, pour l\u2019amiti\u00e9 entre le peuple alg\u00e9rien et le peuple fran\u00e7ais, pour la paix, venez nombreux!<\/p>\n<p>A l\u2019initiative de l&rsquo;ASA 35 et de l\u2019<a href=\"http:\/\/rennes.setif.free.fr\" title=\"Association jumelage Rennes-Setif\" target=\"_blank\">Association de jumelage RENNES-SETIF<\/a>,<br \/>\net le soutien de <a href=\"http:\/\/www.4acg.org\/\" title=\"Anciens Appel\u00e9s en Alg\u00e9rie et leurs Amis Contre la Guerre\" target=\"_blank\">4ACG<\/a> * <a href=\"http:\/\/www.acbbretagne.org\" title=\"Association Culturelle des Berb\u00e8res de Bretagne\" target=\"_blank\">ACBB<\/a> * <a href=\"http:\/\/www.arac.fr\/\" title=\"Association R\u00e9publicaine des Anciens Combattants et Victimes de Guerre\" target=\"_blank\">ARAC<\/a> * FACARO * <a href=\"http:\/\/www.ldh-france.org\/\" title=\"Ligue des droits de l'Homme\" target=\"_blank\">LDH<\/a> * <a href=\"http:\/\/www.mrap.fr\/\" title=\"Mouvement contre le Racisme et pour l\u2019Amiti\u00e9 entre les Peuples\" target=\"_blank\">MRAP<\/a> * Mouvement de la Paix<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ne pas oublier que si le 8 mai est la journ\u00e9e en France de la victoire sur le fascisme c&rsquo;est h\u00e9las aussi la journ\u00e9e de comm\u00e9moration des massacres coloniaux de S\u00e9tif en mai 1945 Mardi 8 mai 2012 14 h 30 Square de S\u00e9tif \u00e0 Rennes (pr\u00e8s de la rue Marc Sangnier) Comm\u00e9moration fraternelle et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[55],"tags":[227,14,9,11,17,18,146],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/509"}],"collection":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/comments?post=509"}],"version-history":[{"count":1,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/509\/revisions"}],"predecessor-version":[{"id":9236,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/509\/revisions\/9236"}],"wp:attachment":[{"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/media?parent=509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/categories?post=509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/tags?post=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}