{"id":8843,"date":"2018-03-15T21:46:30","date_gmt":"2018-03-15T20:46:30","guid":{"rendered":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/?p=8843"},"modified":"2018-03-15T21:46:30","modified_gmt":"2018-03-15T20:46:30","slug":"en-route-pour-le-rassemblement-devant-la-base-de-sous-marins-nucleaires-de-lile-longue-en-octobre-2018","status":"publish","type":"post","link":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/2018\/03\/15\/en-route-pour-le-rassemblement-devant-la-base-de-sous-marins-nucleaires-de-lile-longue-en-octobre-2018\/","title":{"rendered":"En route pour le rassemblement devant la base de sous-marins nucl\u00e9aires de l&rsquo;\u00cele Longue en octobre 2018"},"content":{"rendered":"<h4>Objectif ratification par le plus grand nombre possible d\u2019Etats du trait\u00e9 d\u2019interdiction des armes nucl\u00e9aires<\/h4>\n<p>La deuxi\u00e8me r\u00e9union interr\u00e9gionale des comit\u00e9s du mouvement de la paix en vue de la pr\u00e9paration du rassemblement du 14 octobre 2018 devant la base de sous-marins nucl\u00e9aires de l&rsquo;\u00cele Longue \u00e0 Crozon dans le Finist\u00e8re a eu lieu \u00e0 Rennes le dimanche 11 mars suivant le rythme que nous avons convenu d&rsquo;une r\u00e9union mensuelle collective r\u00e9gional et interr\u00e9gional Bretagne et Ouest.<\/p>\n<p><img data-attachment-id=\"8844\" data-permalink=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/2018\/03\/15\/en-route-pour-le-rassemblement-devant-la-base-de-sous-marins-nucleaires-de-lile-longue-en-octobre-2018\/reunion-interregionale-mvt\/\" data-orig-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/reunion-interregionale-mvt-.jpg\" data-orig-size=\"700,525\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"r\u00e9union interr\u00e9gionale des comit\u00e9s du mouvement de la paix 11 mars 2018\" data-image-description=\"&lt;p&gt;r\u00e9union interr\u00e9gionale des comit\u00e9s du mouvement de la paix 11 mars 2018&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/reunion-interregionale-mvt--300x225.jpg\" data-large-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/reunion-interregionale-mvt-.jpg\" decoding=\"async\" loading=\"lazy\" src=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/reunion-interregionale-mvt-.jpg\" alt=\"r\u00e9union interr\u00e9gionale des comit\u00e9s du mouvement de la paix 11 mars 2018\" width=\"700\" height=\"525\" class=\"alignnone size-full wp-image-8844\" srcset=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/reunion-interregionale-mvt-.jpg 700w, http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/reunion-interregionale-mvt--300x225.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Six d\u00e9partements \u00e9taient repr\u00e9sent\u00e9s. Accord de l&rsquo;ensemble des participants pour faire du 14 octobre un \u00e9v\u00e9nement important dans le cadre de la Journ\u00e9e nationale d&rsquo;action devant les lieux li\u00e9s au nucl\u00e9aire militaire.<\/p>\n<p>Ce sera notre priorit\u00e9 en 2018.<\/p>\n<p>N\u00e9cessit\u00e9 de rassembler l&rsquo;ensemble des organisations syndicales politiques, associatives et les individus autour de l&rsquo;objectif de ratification par la France du trait\u00e9 d&rsquo;interdiction des armes nucl\u00e9aires.<\/p>\n<p>Contacter toutes les associations li\u00e9es \u00e0 ICAN et au collectif national en Marche pour la paix<\/p>\n<p>Des objectifs ambitieux ont \u00e9t\u00e9 fix\u00e9s en termes de flyers, affiches, d\u00e9bats d\u00e9centralis\u00e9s, cr\u00e9ation de comit\u00e9s de Mouvement de la paix, cr\u00e9ation de collectif d\u00e9partementaux ou locaux sur l&rsquo;ensemble de la Bretagne et de l&rsquo;Ouest, adoption d&rsquo;un budget, fixation du d\u00e9roulement de la journ\u00e9e du 14 octobre, campagne de diffusion du film \u00ab\u00a0la Bombe et nous\u00a0\u00bb dans toutes les villes o\u00f9 existe un cin\u00e9ma et ensuite sous forme d&rsquo;activit\u00e9s d&rsquo;\u00e9ducation populaire avec l&rsquo;ensemble des organisations.<\/p>\n<p>Action au moment du vote de la loi de programmation militaire aupr\u00e8s des d\u00e9put\u00e9s<\/p>\n<p>Bonne ambiance, la dynamique est l\u00e0.<\/p>\n<p>PEOCH !!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Objectif ratification par le plus grand nombre possible d\u2019Etats du trait\u00e9 d\u2019interdiction des armes nucl\u00e9aires La deuxi\u00e8me r\u00e9union interr\u00e9gionale des comit\u00e9s du mouvement de la paix en vue de la pr\u00e9paration du rassemblement du 14 octobre 2018 devant la base de sous-marins nucl\u00e9aires de l&rsquo;\u00cele Longue \u00e0 Crozon dans le Finist\u00e8re a eu lieu \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[240,33,159],"tags":[6,29,51,14,9,25,11,96,114],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/8843"}],"collection":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/comments?post=8843"}],"version-history":[{"count":2,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/8843\/revisions"}],"predecessor-version":[{"id":8846,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/8843\/revisions\/8846"}],"wp:attachment":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/media?parent=8843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/categories?post=8843"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/tags?post=8843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}