{"id":5698,"date":"2014-08-11T13:48:36","date_gmt":"2014-08-11T11:48:36","guid":{"rendered":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/?p=5698"},"modified":"2014-08-19T14:15:21","modified_gmt":"2014-08-19T12:15:21","slug":"ouest-france-une-rando-pour-la-paix-au-menez-hom","status":"publish","type":"post","link":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/2014\/08\/11\/ouest-france-une-rando-pour-la-paix-au-menez-hom\/","title":{"rendered":"Ouest France: \u00ab\u00a0Une rando pour la paix au M\u00e9nez-Hom\u00a0\u00bb"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/culturedelapaix.org\/blogs\/festivalpaix\/wp-content\/uploads\/ouestfrancelogo-169x52.png\" alt=\"Ouest France\" width=\"169\" height=\"52\" class=\"alignleft size-full wp-image-85\" \/>Publi\u00e9 dans Ouest France le 9 aout 2014: <a href=\"http:\/\/www.ouest-france.fr\/une-rando-pour-la-paix-au-menez-hom-2753914\" title=\"Ouest France - Une rando pour la paix au M\u00e9nez-Hom\" target=\"_blank\">\u00ab\u00a0Une rando pour la paix au M\u00e9nez-Hom\u00a0\u00bb.<\/a><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<h2>Une rando pour la paix au M\u00e9nez-Hom<\/h2>\n<div id=\"attachment_5700\" style=\"width: 570px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-5700\" data-attachment-id=\"5700\" data-permalink=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/2014\/08\/11\/ouest-france-une-rando-pour-la-paix-au-menez-hom\/140811-rando-pour-la-paix\/\" data-orig-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/140811-rando-pour-la-paix.jpg\" data-orig-size=\"560,315\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Rando pour la paix 2014\" data-image-description=\"&lt;p&gt;Rando pour la paix 2014&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Text&lt;\/p&gt;\n\" data-medium-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/140811-rando-pour-la-paix-300x168.jpg\" data-large-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/140811-rando-pour-la-paix.jpg\" decoding=\"async\" loading=\"lazy\" src=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/140811-rando-pour-la-paix.jpg\" alt=\"Rando pour la paix 2014\" width=\"560\" height=\"315\" class=\"size-full wp-image-5700\" srcset=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/140811-rando-pour-la-paix.jpg 560w, http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/140811-rando-pour-la-paix-300x168.jpg 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><p id=\"caption-attachment-5700\" class=\"wp-caption-text\">\u00c0 droite, No\u00eblle P\u00e9oc&rsquo;h fervente adh\u00e9rente au comit\u00e9 de Concarneau du Mouvement de la paix depuis cinq ans en compagnie de deux sympathisantes de Ch\u00e2teaulin.<\/p><\/div>\n<p><strong>Le Mouvement pour la paix organise une randonn\u00e9e militante au sommet du M\u00e9nez-Hom, dimanche.<\/strong><\/p>\n<p>Ce dimanche, une randonn\u00e9e p\u00e9destre comm\u00e9morative des bombardements atomiques d&rsquo;Hiroshima et de Nagasaki aura lieu au M\u00e9nez-Hom. No\u00eblle P\u00e9oc&rsquo;h adh\u00e9rente au comit\u00e9 de Concarneau du Mouvement de la paix, rencontr\u00e9e au march\u00e9 de Ch\u00e2teaulin pendant une distribution de tracts, est profond\u00e9ment r\u00e9volt\u00e9e.<\/p>\n<p>Et elle veut que cela se sache: <strong>\u00ab\u00a0Les armes nucl\u00e9aires repr\u00e9sentent un r\u00e9el danger. Une erreur humaine est toujours possible. Ce n&rsquo;est pas un hasard si nous avons choisi de d\u00e9buter la randonn\u00e9e au M\u00e9nez-Hom. Il y a une symbolique car ce site surplombe l&rsquo;Ile Longue. Il y a un danger du fait de la pr\u00e9sence de missiles tr\u00e8s puissants dont le dernier en date le M51 qui est extr\u00eamement performant. Mais il faut savoir aussi que des sommes astronomiques sont d\u00e9pens\u00e9es dans les armes atomiques. Le co\u00fbt est scandaleux et moralement inadmissible.\u00a0\u00bb<\/strong> Les passants \u00e0 qui No\u00eblle distribue ses tracts sont g\u00e9n\u00e9ralement compr\u00e9hensifs et d&rsquo;accord avec ses id\u00e9aux: <strong>\u00ab\u00a0On me dit qu&rsquo;il faut continuer de se battre.\u00a0\u00bb<\/strong> Si \u00e0 Ch\u00e2teaulin il y a peu d&rsquo;adh\u00e9rents, on d\u00e9nombre beaucoup de sympathisants.<\/p>\n<p>Dimanche 10 ao\u00fbt, 10h30: randonn\u00e9e avec un d\u00e9part de la st\u00e8le de la r\u00e9sistance, place de Sainte-Marie du M\u00e9nez-Hom. 12h: temps de pique-nique\/d\u00e9bat au sommet du M\u00e9nez-Hom sur la dissuasion nucl\u00e9aire.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publi\u00e9 dans Ouest France le 9 aout 2014: \u00ab\u00a0Une rando pour la paix au M\u00e9nez-Hom\u00a0\u00bb. &nbsp; Une rando pour la paix au M\u00e9nez-Hom Le Mouvement pour la paix organise une randonn\u00e9e militante au sommet du M\u00e9nez-Hom, dimanche. Ce dimanche, une randonn\u00e9e p\u00e9destre comm\u00e9morative des bombardements atomiques d&rsquo;Hiroshima et de Nagasaki aura lieu au M\u00e9nez-Hom. No\u00eblle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[15,56],"tags":[6,14,9,25,11],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/5698"}],"collection":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/comments?post=5698"}],"version-history":[{"count":1,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/5698\/revisions"}],"predecessor-version":[{"id":5701,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/5698\/revisions\/5701"}],"wp:attachment":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/media?parent=5698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/categories?post=5698"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/tags?post=5698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}