{"id":4095,"date":"2013-09-08T18:33:34","date_gmt":"2013-09-08T16:33:34","guid":{"rendered":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/?p=4095"},"modified":"2013-09-08T18:33:34","modified_gmt":"2013-09-08T16:33:34","slug":"ouest-france-la-paix-par-le-dialogue-plus-que-par-les-armes","status":"publish","type":"post","link":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/2013\/09\/08\/ouest-france-la-paix-par-le-dialogue-plus-que-par-les-armes\/","title":{"rendered":"Ouest France: \u00ab\u00a0La paix par le dialogue plus que par les armes\u00a0\u00bb"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/culturedelapaix.org\/blogs\/festivalpaix\/wp-content\/uploads\/ouestfrancelogo-169x52.png\" alt=\"Ouest France\" width=\"169\" height=\"52\" class=\"alignleft size-full wp-image-85\" \/>Publi\u00e9 dans Ouest France le dimanche 1 septembre 2013: <a href=\"http:\/\/www.jactiv.ouest-france.fr\/actualites\/edito-ouest-france\/paix-par-dialogue-plus-que-par-armes-22751\" title=\"Ouest France: La paix par le dialogue plus que par les armes\" target=\"_blank\">\u00ab\u00a0La paix par le dialogue plus que par les armes\u00a0\u00bb<\/a> <\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<h2>EDITO.<br \/>\nLa paix par le dialogue plus que par les armes<\/h2>\n<div id=\"attachment_4096\" style=\"width: 510px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-4096\" data-attachment-id=\"4096\" data-permalink=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/2013\/09\/08\/ouest-france-la-paix-par-le-dialogue-plus-que-par-les-armes\/130908-assad\/\" data-orig-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/130908-assad.png\" data-orig-size=\"500,329\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;&lt;em&gt;&#169; Dessin: Chaunu&lt;\/em&gt;&lt;\/p&gt;\n\" data-medium-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/130908-assad-300x197.png\" data-large-file=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/130908-assad.png\" decoding=\"async\" loading=\"lazy\" src=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/130908-assad.png\" alt=\"&#169; Dessin: Chaunu\" width=\"500\" height=\"329\" class=\"size-full wp-image-4096\" srcset=\"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/130908-assad.png 500w, http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-content\/uploads\/130908-assad-300x197.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><p id=\"caption-attachment-4096\" class=\"wp-caption-text\"><em>&#169; Dessin: Chaunu<\/em><\/p><\/div>\n<p><strong><em>Tout le monde condamne cette abominable agression au gaz qui a caus\u00e9 la mort de plusieurs centaines de personnes en Syrie. \u00c9videmment, il faut sanctionner cette violation du trait\u00e9 de 1925 qui interdit l&rsquo;utilisation de ce type d&rsquo;armes.<\/strong><\/em><\/p>\n<p>Comme l&rsquo;a dit John Kerry, \u00ab\u00a0nous ne pouvons d\u00e9tourner le regard\u00a0\u00bb. C&rsquo;est sur ce principe de base que se fonde l&rsquo;\u00e9ventuelle intervention car il faut \u00e9viter tout risque de prolif\u00e9ration dans ce domaine.<\/p>\n<p>Mais la r\u00e9ponse envisag\u00e9e est-elle appropri\u00e9e? Apr\u00e8s l&rsquo;\u00e9motion qui a suscit\u00e9 les divers mouvements de forces occidentales en M\u00e9diterran\u00e9e, l&rsquo;h\u00e9sitation \u00e9tait survenue. La preuve formelle n&rsquo;est pas encore donn\u00e9e qu&rsquo;il s&rsquo;agit bien d&rsquo;une attaque perp\u00e9tr\u00e9e par le dictateur. Cela a conduit au refus \u00e9mis par le parlement britannique, par l&rsquo;Allemagne, par l&rsquo;Italie&#8230; Cependant, les Am\u00e9ricains sont convaincus de la culpabilit\u00e9 d&rsquo;al-Assad et donnent des \u00e9l\u00e9ments de preuve.<\/p>\n<p>Par ailleurs, le conseil de s\u00e9curit\u00e9 de l&rsquo;Onu est toujours bloqu\u00e9 par les veto russe et chinois. Agir malgr\u00e9 ces veto serait remettre en cause le fonctionnement de l&rsquo;Onu et d\u00e9pr\u00e9cierait cette institution qui marque, malgr\u00e9 ses imperfections, une avanc\u00e9e importante des nations vers la concertation et l&rsquo;entente. Ce serait cr\u00e9er un pr\u00e9c\u00e9dent dangereux pour la paix dans le futur, ce serait ruiner la confiance et l&rsquo;esp\u00e9rance que beaucoup placent heureusement dans cette institution.<\/p>\n<p>Le pr\u00e9sident de l&rsquo;Onu, Ban Ki-moon, a appel\u00e9 \u00e0 la mod\u00e9ration et \u00e0 rechercher d&rsquo;autres moyens pour r\u00e9agir car il voit qu&rsquo;une telle intervention pourrait entra\u00eener de d\u00e9sastreuses cons\u00e9quences pour les populations, la stabilit\u00e9 de la r\u00e9gion, la paix dans le monde&#8230;<\/p>\n<h3>Exiger des couloirs humanitaires<\/h3>\n<p>Il n&rsquo;est d&rsquo;ailleurs pas le seul \u00e0 appeler au calme. Le pape Fran\u00e7ois qui a re\u00e7u, jeudi, le roi Abdallah de Jordanie, estime que <strong>\u00ab\u00a0la voie de la n\u00e9gociation et du dialogue est l&rsquo;unique option\u00a0\u00bb<\/strong>. Il est en plein accord avec les patriarches chr\u00e9tiens de la r\u00e9gion qui redoutent une extension du conflit et craignent les effets collat\u00e9raux des frappes envisag\u00e9es, comme on l&rsquo;a vu dans les conflits afghans et irakiens. Certains, comme Gr\u00e9goire III, le Patriarche gr\u00e9co-melkite d&rsquo;Antioche, d&rsquo;Alexandrie et de J\u00e9rusalem, proclament m\u00eame qu&rsquo;une telle intervention serait <strong>\u00ab\u00a0un acte criminel\u00a0\u00bb<\/strong>!<\/p>\n<p>Tout cela explique bien l&#8217;embarras de ceux qui veulent agir, notamment France et \u00c9tats-Unis qui semblent malgr\u00e9 tout d\u00e9cid\u00e9s \u00e0 entreprendre une action militaire. Ils se sont tellement avanc\u00e9s dans leurs proclamations et leurs gesticulations strat\u00e9giques que, s&rsquo;ils ne faisaient rien, ils perdraient toute cr\u00e9dibilit\u00e9. Voil\u00e0 pourquoi la probabilit\u00e9 d&rsquo;une intervention persiste malgr\u00e9 tous les appels au calme.<\/p>\n<p>Le pr\u00e9sident Hollande a soulign\u00e9, lui aussi, que la v\u00e9ritable solution \u00e0 la crise actuelle ne peut qu&rsquo;\u00eatre politique. C&rsquo;est la sagesse m\u00eame. Mais il n&rsquo;est pas certain que la solution politique soit facilit\u00e9e par la frappe violente envisag\u00e9e par les seuls pays France et \u00c9tats-Unis. Elle pourrait, au contraire, brouiller encore davantage cette situation dramatique.<\/p>\n<p>C&rsquo;est l&rsquo;action diplomatique qui doit primer et la discussion entre tous. Ainsi, le roi de Jordanie convoque une conf\u00e9rence sur la situation des chr\u00e9tiens au Moyen-Orient dont nous connaissons la souffrance. Les diplomates des pays concern\u00e9s devraient, en urgence, faire de m\u00eame et exiger, entre autres, les couloirs humanitaires qui permettraient de soigner et de ravitailler les populations.<\/p>\n<p><em>Fran\u00e7ois R\u00e9gis Hutin<\/em><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publi\u00e9 dans Ouest France le dimanche 1 septembre 2013: \u00ab\u00a0La paix par le dialogue plus que par les armes\u00a0\u00bb &nbsp; EDITO. La paix par le dialogue plus que par les armes Tout le monde condamne cette abominable agression au gaz qui a caus\u00e9 la mort de plusieurs centaines de personnes en Syrie. \u00c9videmment, il faut [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[55,56],"tags":[29,101,170,17,57,109,64],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/4095"}],"collection":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/comments?post=4095"}],"version-history":[{"count":1,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/4095\/revisions"}],"predecessor-version":[{"id":4097,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/posts\/4095\/revisions\/4097"}],"wp:attachment":[{"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/media?parent=4095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/categories?post=4095"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/culturedelapaix.org\/blogs\/Rennes\/wp-json\/wp\/v2\/tags?post=4095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}